{"id":4858,"date":"2021-08-18T17:02:42","date_gmt":"2021-08-18T15:02:42","guid":{"rendered":"https:\/\/geschenke.blogseite.com\/?post_type=product&#038;p=4858"},"modified":"2022-03-31T17:20:49","modified_gmt":"2022-03-31T15:20:49","slug":"joygogo-32-stueck-gleitflugzeuge-%f0%9f%a5%b0","status":"publish","type":"product","link":"https:\/\/www.blogseite.com\/geschenke\/s\/joygogo-32-stueck-gleitflugzeuge-%f0%9f%a5%b0\/","title":{"rendered":"Joygogo 32 St\u00fcck Gleitflugzeuge \ud83e\udd70"},"content":{"rendered":"<p><span class=\"a-list-item\">Mitgebsel Kindergeburtstag : Sie erhalten 8 verschiedene Designs von Segelflugzeug Farben 4 Styroporflieger von jedem Design, jedem Kind und sie werden stundenlang Spa\u00df haben.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mitgebsel Kindergeburtstag : Sie erhalten 8 verschiedene Designs von Segelflugzeug Farben 4 Styroporflieger von jedem Design, jedem Kind und sie werden stundenlang Spa\u00df haben.<\/p>\n","protected":false},"featured_media":4859,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[889,78,87,426,430,431,293,292,302,70,297,295,294],"product_tag":[980,452],"class_list":{"0":"post-4858","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-kinder-2","7":"product_cat-weihnachtsgeschenke","8":"product_cat-kinder","9":"product_cat-nach-preis","10":"product_cat-unter-20-euro","11":"product_cat-unter-50-euro","12":"product_cat-geschenk-fuer-bruder","13":"product_cat-sohn","14":"product_cat--jungen","15":"product_cat-geschenke-fuer-jeden-anlass","16":"product_cat--maedchen","17":"product_cat--tochter","18":"product_cat--schwester","19":"product_tag-flugzeug","20":"product_tag-spielzeug","22":"first","23":"instock","24":"shipping-taxable","25":"product-type-external"},"_links":{"self":[{"href":"https:\/\/www.blogseite.com\/geschenke\/wp-json\/wp\/v2\/product\/4858"}],"collection":[{"href":"https:\/\/www.blogseite.com\/geschenke\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.blogseite.com\/geschenke\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogseite.com\/geschenke\/wp-json\/wp\/v2\/comments?post=4858"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.blogseite.com\/geschenke\/wp-json\/wp\/v2\/media\/4859"}],"wp:attachment":[{"href":"https:\/\/www.blogseite.com\/geschenke\/wp-json\/wp\/v2\/media?parent=4858"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.blogseite.com\/geschenke\/wp-json\/wp\/v2\/product_cat?post=4858"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.blogseite.com\/geschenke\/wp-json\/wp\/v2\/product_tag?post=4858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}